{"id":665,"date":"2024-10-07T14:38:04","date_gmt":"2024-10-07T07:38:04","guid":{"rendered":"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/?p=665"},"modified":"2026-03-13T09:48:31","modified_gmt":"2026-03-13T02:48:31","slug":"%e0%b8%ab%e0%b8%a1%e0%b8%ad%e0%b8%a5%e0%b8%b3%e0%b8%ad%e0%b8%a7%e0%b8%a2%e0%b8%9e%e0%b8%a3-%e0%b8%9e%e0%b8%a3%e0%b8%ab%e0%b8%a1%e0%b8%97%e0%b8%ad%e0%b8%87","status":"publish","type":"post","link":"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/index.php\/2024\/10\/07\/%e0%b8%ab%e0%b8%a1%e0%b8%ad%e0%b8%a5%e0%b8%b3%e0%b8%ad%e0%b8%a7%e0%b8%a2%e0%b8%9e%e0%b8%a3-%e0%b8%9e%e0%b8%a3%e0%b8%ab%e0%b8%a1%e0%b8%97%e0%b8%ad%e0%b8%87\/","title":{"rendered":"\u0e2b\u0e21\u0e2d\u0e25\u0e33\u0e2d\u0e27\u0e22\u0e1e\u0e23 \u0e1e\u0e23\u0e2b\u0e21\u0e17\u0e2d\u0e07"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"665\" class=\"elementor elementor-665\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d32fcbb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1d32fcbb\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-30d6c8ab\" data-id=\"30d6c8ab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4390f19 elementor-widget elementor-widget-image\" data-id=\"4390f19\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"725\" height=\"1024\" src=\"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/10\/\u0e2b\u0e21\u0e2d\u0e25\u0e33\u0e2d\u0e27\u0e22\u0e1e\u0e23-\u0e1e\u0e23\u0e2b\u0e21\u0e17\u0e2d\u0e07.png\" class=\"attachment-large size-large wp-image-701\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7e2b0aba\" data-id=\"7e2b0aba\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12d235f elementor-widget elementor-widget-text-editor\" data-id=\"12d235f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>\u0e0a\u0e37\u0e48\u0e2d\u0e43\u0e19\u0e27\u0e07\u0e01\u0e32\u0e23 :<\/strong> \u0e2b\u0e21\u0e2d\u0e25\u0e33\u0e2d\u0e27\u0e22\u0e1e\u0e23 \u0e1e\u0e23\u0e2b\u0e21\u0e17\u0e2d\u0e07<\/p><p><b>\u0e0a\u0e37\u0e48\u0e2d &#8211; \u0e2a\u0e01\u0e38\u0e25 :<\/b> \u0e19.\u0e2a.\u0e17\u0e2d\u0e07\u0e04\u0e33 \u0e25\u0e37\u0e2d\u0e42\u0e2a\u0e20\u0e32<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efe8935 elementor-widget elementor-widget-text-editor\" data-id=\"efe8935\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d : <\/strong>062 &#8211; 2342654, 0878581126<\/p><p><strong>\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48 : <\/strong>\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e2d\u0e07\u0e2b\u0e34\u0e19 \u0e15.\u0e2b\u0e31\u0e27\u0e14\u0e07 \u0e2d.\u0e19\u0e32\u0e14\u0e39\u0e19 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-207a5a5 elementor-widget elementor-widget-text-editor\" data-id=\"207a5a5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d : \u00a0<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94eea92 elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"94eea92\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/www.facebook.com\/profile.php?id=100083874002557\">\n\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook-square\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99c04cb elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"99c04cb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.facebook.com\/profile.php?id=100083874002557\">\u0e2d\u0e27\u0e22\u0e1e\u0e23 \u0e1e\u0e23\u0e2b\u0e21\u0e17\u0e2d\u0e07 \u0e25\u0e37\u0e2d\u0e42\u0e2a\u0e20\u0e32 <\/a><\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df0bcea elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"df0bcea\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/www.youtube.com\/@%E0%B8%AD%E0%B8%A7%E0%B8%A2%E0%B8%9E%E0%B8%A3%E0%B8%9E%E0%B8%A3%E0%B8%AB%E0%B8%A1%E0%B8%97%E0%B8%AD%E0%B8%87\">\n\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22664f1 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"22664f1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.youtube.com\/@%E0%B8%AD%E0%B8%A7%E0%B8%A2%E0%B8%9E%E0%B8%A3%E0%B8%9E%E0%B8%A3%E0%B8%AB%E0%B8%A1%E0%B8%97%E0%B8%AD%E0%B8%87\">\u0e2d\u0e27\u0e22\u0e1e\u0e23 \u0e1e\u0e23\u0e2b\u0e21\u0e17\u0e2d\u0e07<\/a><\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8b8fc54 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8b8fc54\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f1fd7ce\" data-id=\"f1fd7ce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0bde6c2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0bde6c2\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47d84b2e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47d84b2e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-643954eb\" data-id=\"643954eb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6c6269db elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c6269db\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9635c31\" data-id=\"9635c31\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73e5243 elementor-widget elementor-widget-heading\" data-id=\"73e5243\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e04\u0e25\u0e34\u0e1a\u0e27\u0e34\u0e14\u0e34\u0e42\u0e2d<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33805814 elementor-widget elementor-widget-text-editor\" data-id=\"33805814\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e1a\u0e17\u0e2a\u0e31\u0e21\u0e20\u0e32\u0e29\u0e13\u0e4c\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-67e713b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"67e713b\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a75416\" data-id=\"4a75416\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a506e36 elementor-widget elementor-widget-eael-sticky-video\" data-id=\"a506e36\" data-element_type=\"widget\" data-widget_type=\"eael-sticky-video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"eael-sticky-video-wrapper eaelsv-overlay-visibility-\"><div class=\"eael-sticky-video-player2\" data-sticky=\"yes\" data-position=\"bottom-right\" data-sheight=\"169\" data-swidth=\"300\" data-scroll_height=\"70\" data-autoplay=\"no\" data-overlay=\"no\">\n\t\t\t\t<div\n\t\t\tid=\"eaelsv-player-a506e36\"\n\t\t\tdata-plyr-provider=\"youtube\"\n\t\t\tdata-plyr-embed-id=\"OlierEbFCf4\"\n\t\t\tdata-plyr-config=\"{&quot;storage&quot;: {&quot;enabled&quot;: false, &quot;key&quot;: &quot;plyr&quot;}, &quot;autoplay&quot;:0, &quot;muted&quot;:0, &quot;loop&quot;: {&quot;active&quot;: false}}\"\n\t\t><\/div>\n\t\t\t\t<span class=\"eaelsv-sticky-player-close\"><i class=\"fas fa-times-circle\"><\/i><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78c832a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"78c832a\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-739e9a17 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"739e9a17\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6e2cc09\" data-id=\"6e2cc09\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7953656f elementor-widget elementor-widget-heading\" data-id=\"7953656f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u0e2d\u0e31\u0e25\u0e1a\u0e31\u0e49\u0e21\u0e20\u0e32\u0e1e<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-298e4555 elementor-widget elementor-widget-text-editor\" data-id=\"298e4555\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Multi color icon with border outline<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c038ac1\" data-id=\"c038ac1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34a3b3d elementor-widget elementor-widget-aux-gallery\" data-id=\"34a3b3d\" data-element_type=\"widget\" data-widget_type=\"aux-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-gallery aux-parent-aud0753bc3\"><div id='aux-gallery-1' class='aux-gallery galleryid-665 gallery-columns-4 aux-lightbox-gallery'><div class=\"aux-gallery-container aux-isotope-animated aux-row aux-de-col4 aux-tb-col2 aux-mb-col1 elementor-clickable aux-no-gutter aux-layout-masonry\"  data-pagination=\"false\" data-lazyload=\"false\" data-perpage=\"24\" data-layout=\"masonry\" data-space=\"10\" >    <figure class=\"gallery-item aux-hover-active aux-iso-item aux-col \">\n            <div class=\"aux-frame-mask-plain aux-frame-ratio \">\n                <a href=\"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/09\/11-\u0e1e\u0e48\u0e2d\u0e21\u0e35\u0e24\u0e17\u0e18\u0e34\u0e4c-\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e27\u0e07\u0e28\u0e4c.png\" class=\"aux-frame-ratio-inner aux-frame-darken aux-lightbox-btn \" data-elementor-open-lightbox=\"no\" data-original-width=\"1655\" data-original-height=\"2338\" data-caption=\"11 \u0e1e\u0e48\u0e2d\u0e21\u0e35\u0e24\u0e17\u0e18\u0e34\u0e4c \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e27\u0e07\u0e28\u0e4c\">\n                                <div class=\"aux-hover-scale-circle-plus2\">\n                        <span class=\"aux-symbol-plus\"><\/span>\n                        <span class=\"aux-symbol-circle\"><\/span>\n                    <\/div>\n                        <img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/09\/11-\u0e1e\u0e48\u0e2d\u0e21\u0e35\u0e24\u0e17\u0e18\u0e34\u0e4c-\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e27\u0e07\u0e28\u0e4c-300x300.png\" class=\"aux-attachment aux-featured-image attachment-300x300 aux-attachment-id-520 \" alt=\"11 \u0e1e\u0e48\u0e2d\u0e21\u0e35\u0e24\u0e17\u0e18\u0e34\u0e4c \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e27\u0e07\u0e28\u0e4c\" srcset=\"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/09\/11-\u0e1e\u0e48\u0e2d\u0e21\u0e35\u0e24\u0e17\u0e18\u0e34\u0e4c-\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e27\u0e07\u0e28\u0e4c-150x150.png 150w,https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/09\/11-\u0e1e\u0e48\u0e2d\u0e21\u0e35\u0e24\u0e17\u0e18\u0e34\u0e4c-\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e27\u0e07\u0e28\u0e4c-300x300.png 300w,https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/09\/11-\u0e1e\u0e48\u0e2d\u0e21\u0e35\u0e24\u0e17\u0e18\u0e34\u0e4c-\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e27\u0e07\u0e28\u0e4c-768x768.png 768w,https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/09\/11-\u0e1e\u0e48\u0e2d\u0e21\u0e35\u0e24\u0e17\u0e18\u0e34\u0e4c-\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e27\u0e07\u0e28\u0e4c-1024x1024.png 1024w,https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/09\/11-\u0e1e\u0e48\u0e2d\u0e21\u0e35\u0e24\u0e17\u0e18\u0e34\u0e4c-\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e27\u0e07\u0e28\u0e4c-300x300.png 300w,https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/09\/11-\u0e1e\u0e48\u0e2d\u0e21\u0e35\u0e24\u0e17\u0e18\u0e34\u0e4c-\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e27\u0e07\u0e28\u0e4c-1645x1645.png 1645w\" data-ratio=\"1\" data-original-w=\"1655\" sizes=\"(max-width:767px) 100vw,(min-width:768px) and (max-width:1025px) 50vw,380px\" \/>                <\/a>\n            <\/div>\n                <\/figure>\n<\/div><\/div><\/section><!-- widget-container --><style>.aux-parent-aud0753bc3 .aux-frame-ratio { padding-bottom:75% }<\/style>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-241bf22 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"241bf22\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f32a7cd\" data-id=\"f32a7cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0e0a\u0e37\u0e48\u0e2d\u0e43\u0e19\u0e27\u0e07\u0e01\u0e32\u0e23 : \u0e2b\u0e21\u0e2d\u0e25\u0e33\u0e2d\u0e27\u0e22\u0e1e\u0e23 \u0e1e\u0e23\u0e2b\u0e21\u0e17\u0e2d\u0e07 \u0e0a\u0e37\u0e48\u0e2d &#8211; \u0e2a\u0e01\u0e38\u0e25 : \u0e19.\u0e2a.\u0e17\u0e2d\u0e07\u0e04\u0e33 \u0e25\u0e37\u0e2d\u0e42\u0e2a\u0e20\u0e32 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d : 062 &#8211; 2342654, 0878581126 \u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48 : \u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e2d\u0e07\u0e2b\u0e34\u0e19 \u0e15.\u0e2b\u0e31\u0e27\u0e14\u0e07 \u0e2d.\u0e19\u0e32\u0e14\u0e39\u0e19 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d : \u00a0 \u0e2d\u0e27\u0e22\u0e1e\u0e23 \u0e1e\u0e23\u0e2b\u0e21\u0e17\u0e2d\u0e07 \u0e25\u0e37\u0e2d\u0e42\u0e2a\u0e20\u0e32 \u0e2d\u0e27\u0e22\u0e1e\u0e23 \u0e1e\u0e23\u0e2b\u0e21\u0e17\u0e2d\u0e07 \u0e04\u0e25\u0e34\u0e1a\u0e27\u0e34\u0e14\u0e34\u0e42\u0e2d \u0e1a\u0e17\u0e2a\u0e31\u0e21\u0e20\u0e32\u0e29\u0e13\u0e4c\u00a0 \u0e2d\u0e31\u0e25\u0e1a\u0e31\u0e49\u0e21\u0e20\u0e32\u0e1e Multi color icon with border outline<\/p>\n","protected":false},"author":2,"featured_media":708,"comment_status":"closed","ping_status":"open","sticky":false,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-morlam-artist"],"_links":{"self":[{"href":"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/index.php\/wp-json\/wp\/v2\/posts\/665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/index.php\/wp-json\/wp\/v2\/comments?post=665"}],"version-history":[{"count":23,"href":"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/index.php\/wp-json\/wp\/v2\/posts\/665\/revisions"}],"predecessor-version":[{"id":704,"href":"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/index.php\/wp-json\/wp\/v2\/posts\/665\/revisions\/704"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/index.php\/wp-json\/wp\/v2\/media\/708"}],"wp:attachment":[{"href":"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/index.php\/wp-json\/wp\/v2\/media?parent=665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/index.php\/wp-json\/wp\/v2\/categories?post=665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/index.php\/wp-json\/wp\/v2\/tags?post=665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}