{"id":129,"date":"2024-08-12T16:39:20","date_gmt":"2024-08-12T16:39:20","guid":{"rendered":"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/?p=129"},"modified":"2026-03-13T09:48:32","modified_gmt":"2026-03-13T02:48:32","slug":"%e0%b9%80%e0%b8%94%e0%b8%b7%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d-%e0%b8%ad%e0%b8%b3%e0%b8%99%e0%b8%a7%e0%b8%a2%e0%b8%9e%e0%b8%a3","status":"publish","type":"post","link":"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/index.php\/2024\/08\/12\/%e0%b9%80%e0%b8%94%e0%b8%b7%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d-%e0%b8%ad%e0%b8%b3%e0%b8%99%e0%b8%a7%e0%b8%a2%e0%b8%9e%e0%b8%a3\/","title":{"rendered":"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e40\u0e1e\u0e47\u0e0d \u0e2d\u0e33\u0e19\u0e27\u0e22\u0e1e\u0e23"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"129\" class=\"elementor elementor-129\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d32fcbb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1d32fcbb\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-30d6c8ab\" data-id=\"30d6c8ab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4390f19 elementor-widget elementor-widget-image\" data-id=\"4390f19\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/01-\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e40\u0e1e\u0e47\u0e0d-\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e1e\u0e23-1024x1024.png\" class=\"attachment-large size-large wp-image-69\" alt=\"\" srcset=\"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/01-\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e40\u0e1e\u0e47\u0e0d-\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e1e\u0e23-1024x1024.png 1024w, https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/01-\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e40\u0e1e\u0e47\u0e0d-\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e1e\u0e23-300x300.png 300w, https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/01-\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e40\u0e1e\u0e47\u0e0d-\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e1e\u0e23-150x150.png 150w, https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/01-\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e40\u0e1e\u0e47\u0e0d-\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e1e\u0e23-768x768.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7e2b0aba\" data-id=\"7e2b0aba\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12d235f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"12d235f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>\u0e0a\u0e37\u0e48\u0e2d\u0e43\u0e19\u0e27\u0e07\u0e01\u0e32\u0e23 :<\/strong> \u0e40\u0e14\u0e37\u0e2d\u0e19\u0e40\u0e1e\u0e47\u0e0d\u00a0 \u0e2d\u0e33\u0e19\u0e27\u0e22\u0e1e\u0e23<br \/><strong>\u0e0a\u0e37\u0e48\u0e2d\u0e08\u0e23\u0e34\u0e07 : <\/strong>\u0e2d\u0e33\u0e19\u0e27\u0e22 \u00a0\u0e08\u0e31\u0e19\u0e42\u0e17\u0e2a\u0e35<br \/><strong>\u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e04\u0e13\u0e30\u0e2b\u0e21\u0e2d\u0e25\u0e33 : <\/strong><a href=\"https:\/\/www.facebook.com\/Mohlumwongjaroen\">\u0e27\u0e07\u0e29\u0e4c\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e28\u0e34\u0e25\u0e1b\u0e4c\u00a0<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efe8935 elementor-widget elementor-widget-text-editor\" data-id=\"efe8935\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d : 087 &#8211; 945 &#8211; 9649<br \/><\/strong><strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0089 &#8211; 570 &#8211; 2483<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-207a5a5 elementor-widget elementor-widget-text-editor\" data-id=\"207a5a5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e25\u0e07\u0e17\u0e35\u0e48\u0e19\u0e34\u0e22\u0e21 :\u00a0 <\/strong><a href=\"https:\/\/www.youtube.com\/watch?v=gdrzAVI_CnQ\">\u0e2a\u0e32\u0e27\u0e19\u0e32\u0e02\u0e32\u0e14\u0e23\u0e31\u0e01<\/a><br \/>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=OP_XNf1GNX0\">\u0e04\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e22\u0e31\u0e07\u0e04\u0e2d\u0e22<\/a><br \/>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=NLqRjuQDgIM\">\u0e19\u0e49\u0e33\u0e15\u0e32\u0e2a\u0e32\u0e27\u0e40\u0e22\u0e47\u0e1a\u0e1c\u0e49\u0e32<\/a><br \/>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=5tto_su-6i8\">\u0e04\u0e32\u0e19\u0e17\u0e2d\u0e07\u0e2b\u0e49\u0e2d\u0e07\u0e41\u0e2d\u0e23\u0e4c<\/a><br \/>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=6TrSo_ZEkT0\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e2b\u0e23\u0e48\u0e08\u0e30\u0e1e\u0e2d<\/a><br \/>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=Uygx8b2g5b0\">\u0e23\u0e31\u0e01\u0e41\u0e17\u0e49\u0e41\u0e1e\u0e49\u0e25\u0e31\u0e1a\u0e2b\u0e25\u0e31\u0e07<\/a><br \/>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 <a href=\"https:\/\/www.youtube.com\/watch?v=MS7afS7CJBQ\">\u00a0\u0e2a\u0e39\u0e49\u0e40\u0e02\u0e32\u0e44\u0e14\u0e49\u0e41\u0e04\u0e48\u0e43\u0e08\u0e17\u0e35\u0e48\u0e23\u0e31\u0e01\u0e08\u0e23\u0e34\u0e07<\/a><br \/>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=1EPRiPK7OWw\">\u0e08\u0e30\u0e23\u0e31\u0e01\u0e40\u0e18\u0e2d\u0e08\u0e19\u0e2a\u0e34\u0e49\u0e19\u0e43\u0e08<\/a><br \/>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 <a href=\"https:\/\/www.youtube.com\/watch?v=lGZm3pZKcjA\">\u0e01\u0e31\u0e1a\u0e19\u0e49\u0e2d\u0e07\u0e41\u0e04\u0e48\u0e40\u0e2b\u0e07\u0e32 \u0e01\u0e31\u0e1a\u0e40\u0e02\u0e32\u0e15\u0e25\u0e2d\u0e14\u0e40\u0e27\u0e25\u0e32<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ec7949 e-grid-align-left elementor-widget__width-initial elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"9ec7949\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-aba4617\" href=\"https:\/\/www.facebook.com\/profile.php?id=100010663156899\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42b1c84 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"42b1c84\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.facebook.com\/profile.php?id=100010663156899\">\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e40\u0e1e\u0e47\u0e0d \u0e2d\u0e33\u0e19\u0e27\u0e22\u0e1e\u0e23<\/a><\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-383e976 e-grid-align-left elementor-widget__width-initial elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"383e976\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-aba4617\" href=\"https:\/\/www.youtube.com\/channel\/UCTvrI0ujwksHliP1BARoXLg\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce48065 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"ce48065\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.youtube.com\/channel\/UCTvrI0ujwksHliP1BARoXLg\">\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e40\u0e1e\u0e47\u0e0d \u0e2d\u0e33\u0e19\u0e27\u0e22\u0e1e\u0e23<\/a><\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8b8fc54 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8b8fc54\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f1fd7ce\" data-id=\"f1fd7ce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0bde6c2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0bde6c2\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47d84b2e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47d84b2e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-643954eb\" data-id=\"643954eb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6c6269db elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c6269db\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9635c31\" data-id=\"9635c31\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73e5243 elementor-widget elementor-widget-heading\" data-id=\"73e5243\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e04\u0e25\u0e34\u0e1a\u0e27\u0e34\u0e14\u0e34\u0e42\u0e2d<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33805814 elementor-widget elementor-widget-text-editor\" data-id=\"33805814\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0e1a\u0e17\u0e2a\u0e31\u0e21\u0e20\u0e32\u0e29\u0e13\u0e4c\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a506e36 elementor-widget elementor-widget-eael-sticky-video\" data-id=\"a506e36\" data-element_type=\"widget\" data-widget_type=\"eael-sticky-video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"eael-sticky-video-wrapper eaelsv-overlay-visibility-\"><div class=\"eael-sticky-video-player2\" data-sticky=\"yes\" data-position=\"bottom-right\" data-sheight=\"169\" data-swidth=\"300\" data-scroll_height=\"70\" data-autoplay=\"no\" data-overlay=\"no\">\n\t\t\t\t<div\n\t\t\tid=\"eaelsv-player-a506e36\"\n\t\t\tdata-plyr-provider=\"youtube\"\n\t\t\tdata-plyr-embed-id=\"G9zYMkCxEQw\"\n\t\t\tdata-plyr-config=\"{&quot;storage&quot;: {&quot;enabled&quot;: false, &quot;key&quot;: &quot;plyr&quot;}, &quot;autoplay&quot;:0, &quot;muted&quot;:0, &quot;loop&quot;: {&quot;active&quot;: false}}\"\n\t\t><\/div>\n\t\t\t\t<span class=\"eaelsv-sticky-player-close\"><i class=\"fas fa-times-circle\"><\/i><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-67e713b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"67e713b\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a75416\" data-id=\"4a75416\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78c832a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"78c832a\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-739e9a17 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"739e9a17\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6e2cc09\" data-id=\"6e2cc09\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7953656f elementor-widget elementor-widget-heading\" data-id=\"7953656f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u0e2d\u0e31\u0e25\u0e1a\u0e31\u0e49\u0e21\u0e20\u0e32\u0e1e<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-298e4555 elementor-widget elementor-widget-text-editor\" data-id=\"298e4555\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Multi color icon with border outline<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c038ac1\" data-id=\"c038ac1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34a3b3d elementor-widget elementor-widget-aux-gallery\" data-id=\"34a3b3d\" data-element_type=\"widget\" data-widget_type=\"aux-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-gallery aux-parent-au19e4962b\"><div id='aux-gallery-1' class='aux-gallery galleryid-129 gallery-columns-4 aux-lightbox-gallery'><div class=\"aux-gallery-container aux-isotope-animated aux-row aux-de-col4 aux-tb-col2 aux-mb-col1 elementor-clickable aux-no-gutter aux-layout-masonry\"  data-pagination=\"false\" data-lazyload=\"false\" data-perpage=\"24\" data-layout=\"masonry\" data-space=\"10\" >    <figure class=\"gallery-item aux-hover-active aux-iso-item aux-col \">\n            <div class=\"aux-frame-mask-plain aux-frame-ratio \">\n                <a href=\"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/s_162647_4269.jpg\" class=\"aux-frame-ratio-inner aux-frame-darken aux-lightbox-btn \" data-elementor-open-lightbox=\"no\" data-original-width=\"1200\" data-original-height=\"630\" data-caption=\"s_162647_4269\">\n                                <div class=\"aux-hover-scale-circle-plus2\">\n                        <span class=\"aux-symbol-plus\"><\/span>\n                        <span class=\"aux-symbol-circle\"><\/span>\n                    <\/div>\n                        <img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/s_162647_4269-300x300.jpg\" class=\"aux-attachment aux-featured-image attachment-300x300 aux-attachment-id-136 \" alt=\"s_162647_4269\" srcset=\"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/s_162647_4269-150x150.jpg 150w,https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/s_162647_4269-300x300.jpg 300w,https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/s_162647_4269-768x630.jpg 768w,https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/s_162647_4269-1024x630.jpg 1024w,https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/s_162647_4269-300x300.jpg 300w,https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/s_162647_4269-1190x1190.jpg 1190w\" data-ratio=\"1\" data-original-w=\"1200\" sizes=\"(max-width:767px) 100vw,(min-width:768px) and (max-width:1025px) 50vw,380px\" \/>                <\/a>\n            <\/div>\n                <\/figure>\n    <figure class=\"gallery-item aux-hover-active aux-iso-item aux-col \">\n            <div class=\"aux-frame-mask-plain aux-frame-ratio \">\n                <a href=\"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/1900x1900-000000-80-0-0.jpg\" class=\"aux-frame-ratio-inner aux-frame-darken aux-lightbox-btn \" data-elementor-open-lightbox=\"no\" data-original-width=\"1200\" data-original-height=\"1200\" data-caption=\"1900x1900-000000-80-0-0\">\n                                <div class=\"aux-hover-scale-circle-plus2\">\n                        <span class=\"aux-symbol-plus\"><\/span>\n                        <span class=\"aux-symbol-circle\"><\/span>\n                    <\/div>\n                        <img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/1900x1900-000000-80-0-0-300x300.jpg\" class=\"aux-attachment aux-featured-image attachment-300x300 aux-attachment-id-134 \" alt=\"1900x1900-000000-80-0-0\" srcset=\"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/1900x1900-000000-80-0-0-150x150.jpg 150w,https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/1900x1900-000000-80-0-0-300x300.jpg 300w,https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/1900x1900-000000-80-0-0-768x768.jpg 768w,https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/1900x1900-000000-80-0-0-1024x1024.jpg 1024w,https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/1900x1900-000000-80-0-0-300x300.jpg 300w,https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/1900x1900-000000-80-0-0-1190x1190.jpg 1190w\" data-ratio=\"1\" data-original-w=\"1200\" sizes=\"(max-width:767px) 100vw,(min-width:768px) and (max-width:1025px) 50vw,380px\" \/>                <\/a>\n            <\/div>\n                <\/figure>\n    <figure class=\"gallery-item aux-hover-active aux-iso-item aux-col \">\n            <div class=\"aux-frame-mask-plain aux-frame-ratio \">\n                <a href=\"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/01-\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e40\u0e1e\u0e47\u0e0d-\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e1e\u0e23.png\" class=\"aux-frame-ratio-inner aux-frame-darken aux-lightbox-btn \" data-elementor-open-lightbox=\"no\" data-original-width=\"1655\" data-original-height=\"2338\" data-caption=\"01 \u0e40\u0e14\u0e37\u0e2d\u0e19\u0e40\u0e1e\u0e47\u0e0d-\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e1e\u0e23\">\n                                <div class=\"aux-hover-scale-circle-plus2\">\n                        <span class=\"aux-symbol-plus\"><\/span>\n                        <span class=\"aux-symbol-circle\"><\/span>\n                    <\/div>\n                        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/01-\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e40\u0e1e\u0e47\u0e0d-\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e1e\u0e23-300x300.png\" class=\"aux-attachment aux-featured-image attachment-300x300 aux-attachment-id-69 \" alt=\"01 \u0e40\u0e14\u0e37\u0e2d\u0e19\u0e40\u0e1e\u0e47\u0e0d-\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e1e\u0e23\" srcset=\"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/01-\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e40\u0e1e\u0e47\u0e0d-\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e1e\u0e23-150x150.png 150w,https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/01-\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e40\u0e1e\u0e47\u0e0d-\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e1e\u0e23-300x300.png 300w,https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/01-\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e40\u0e1e\u0e47\u0e0d-\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e1e\u0e23-768x768.png 768w,https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/01-\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e40\u0e1e\u0e47\u0e0d-\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e1e\u0e23-1024x1024.png 1024w,https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/01-\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e40\u0e1e\u0e47\u0e0d-\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e1e\u0e23-300x300.png 300w,https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/wp-content\/uploads\/2024\/08\/01-\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e40\u0e1e\u0e47\u0e0d-\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e1e\u0e23-1645x1645.png 1645w\" data-ratio=\"1\" data-original-w=\"1655\" sizes=\"(max-width:767px) 100vw,(min-width:768px) and (max-width:1025px) 50vw,380px\" \/>                <\/a>\n            <\/div>\n                <\/figure>\n<\/div><\/div><\/section><!-- widget-container --><style>.aux-parent-au19e4962b .aux-frame-ratio { padding-bottom:75% }<\/style>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0e0a\u0e37\u0e48\u0e2d\u0e43\u0e19\u0e27\u0e07\u0e01\u0e32\u0e23 : \u0e40\u0e14\u0e37\u0e2d\u0e19\u0e40\u0e1e\u0e47\u0e0d\u00a0 \u0e2d\u0e33\u0e19\u0e27\u0e22\u0e1e\u0e23\u0e0a\u0e37\u0e48\u0e2d\u0e08\u0e23\u0e34\u0e07 : \u0e2d\u0e33\u0e19\u0e27\u0e22 \u00a0\u0e08\u0e31\u0e19\u0e42\u0e17\u0e2a\u0e35\u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e04\u0e13\u0e30\u0e2b\u0e21\u0e2d\u0e25\u0e33 : \u0e27\u0e07\u0e29\u0e4c\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e28\u0e34\u0e25\u0e1b\u0e4c\u00a0 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d : 087 &#8211; 945 &#8211; 9649\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0089 &#8211; 570 &#8211; 2483 \u0e1c\u0e25\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e25\u0e07\u0e17\u0e35\u0e48\u0e19\u0e34\u0e22\u0e21 :\u00a0 \u0e2a\u0e32\u0e27\u0e19\u0e32\u0e02\u0e32\u0e14\u0e23\u0e31\u0e01\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u0e04\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e22\u0e31\u0e07\u0e04\u0e2d\u0e22\u00a0 \u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":69,"comment_status":"closed","ping_status":"open","sticky":false,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-morlam-artist"],"_links":{"self":[{"href":"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/index.php\/wp-json\/wp\/v2\/posts\/129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/index.php\/wp-json\/wp\/v2\/comments?post=129"}],"version-history":[{"count":76,"href":"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/index.php\/wp-json\/wp\/v2\/posts\/129\/revisions"}],"predecessor-version":[{"id":557,"href":"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/index.php\/wp-json\/wp\/v2\/posts\/129\/revisions\/557"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/index.php\/wp-json\/wp\/v2\/media\/69"}],"wp:attachment":[{"href":"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/index.php\/wp-json\/wp\/v2\/media?parent=129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/index.php\/wp-json\/wp\/v2\/categories?post=129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arit.rmu.ac.th\/%E0%B8%AB%E0%B8%A1%E0%B8%AD%E0%B8%A5%E0%B8%B3\/index.php\/wp-json\/wp\/v2\/tags?post=129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}